{"id":12610,"date":"2024-01-15T00:00:00","date_gmt":"2024-01-15T00:00:00","guid":{"rendered":"https:\/\/digitalhumanlibrary.com\/meet-new-dhl-mindfulness-expert-and-author-brad-hutchinson\/"},"modified":"2024-01-15T00:00:00","modified_gmt":"2024-01-15T00:00:00","slug":"meet-new-dhl-mindfulness-expert-and-author-brad-hutchinson","status":"publish","type":"post","link":"https:\/\/digitalhumanlibrary.com\/fr\/meet-new-dhl-mindfulness-expert-and-author-brad-hutchinson\/","title":{"rendered":"D\u00e9couvrez Brad Hutchinson, nouvel expert en pleine conscience et auteur chez DHL"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Des classes ax\u00e9es sur la pleine conscience<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignleft size-full is-resized\"><img decoding=\"async\" src=\"http:\/\/antiquewhite-albatross-611666.hostingersite.com\/wp-content\/uploads\/2023\/12\/EDN85lvL_400x400.jpg\" alt=\"\" class=\"wp-image-15810\" style=\"aspect-ratio:1;width:215px;height:auto\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le paysage \u00e9ducatif en constante \u00e9volution, il n\u2019a jamais \u00e9t\u00e9 aussi crucial de cultiver la r\u00e9silience, la compassion et la conscience de soi chez les \u00e9l\u00e8ves. Brad Hutchinson, leader communautaire chevronn\u00e9 fort de plus de deux d\u00e9cennies de pratiques transformatrices, s'impose comme un guide dans cette d\u00e9marche. En tant que professeur de kung-fu Shaolin, auteur et d\u00e9fenseur du bien-\u00eatre des \u00e9l\u00e8ves et du personnel, Hutchinson apporte une mine de connaissances et d'exp\u00e9rience pour favoriser le bien-\u00eatre, la d\u00e9brouillardise et le renforcement des capacit\u00e9s au sein des classes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au milieu du tourbillon des pressions scolaires et sociales qui r\u00e8gnent dans les \u00e9tablissements, la pleine conscience appara\u00eet comme une lueur d\u2019espoir et de r\u00e9silience. Encourager la pratique de la pleine conscience offre aux \u00e9l\u00e8ves un outil puissant pour g\u00e9rer le stress, cultiver leur r\u00e9silience et apporter davantage de joie et de bonheur \u00e0 leur exp\u00e9rience d\u2019apprentissage. En favorisant la conscience du moment pr\u00e9sent, les \u00e9l\u00e8ves peuvent se lib\u00e9rer du cercle vicieux des pens\u00e9es et des \u00e9motions n\u00e9fastes concernant l\u2019avenir\u2026 ou des sentiments d\u2019\u00e9chec. La pleine conscience offre une pause, un souffle au milieu du chaos, permettant aux \u00e9l\u00e8ves de g\u00e9rer leur stress avec clart\u00e9 et s\u00e9r\u00e9nit\u00e9. L\u2019int\u00e9gration de pratiques de pleine conscience dans le cadre scolaire public favorise non seulement le bien-\u00eatre mental, mais dote \u00e9galement les \u00e9l\u00e8ves de comp\u00e9tences qui leur serviront toute leur vie pour s\u2019\u00e9panouir face aux d\u00e9fis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brad propose les pratiques S.I.M.P.L.E. aux \u00e9l\u00e8ves et aux enseignants. (Setting In Motion Powerful Liberating Events) gr\u00e2ce au pouvoir de P.A.U.S.E. (Providing Attention Unveils Special Experiences). Ses interventions allient explication et exp\u00e9rience, c'est-\u00e0-dire qu'elles combinent des discours inspirants et des pratiques de pleine conscience.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Le coin des auteurs, niveaux CM1-5e : susciter l'int\u00e9r\u00eat pour la litt\u00e9rature<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Embarquez vos \u00e9l\u00e8ves dans un voyage litt\u00e9raire en compagnie de l\u2019auteur Brad Hutchinson. Observez leurs visages s\u2019illuminer de compr\u00e9hension lorsque des concepts abstraits tels que le travail d\u2019\u00e9quipe, la responsabilit\u00e9 ou le courage prennent tout leur sens \u00e0 travers une histoire d\u2019aventure au rythme effr\u00e9n\u00e9. \u2019 The Eye of the Storm \u201c trouve un \u00e9cho tant aupr\u00e8s des enseignants que des \u00e9l\u00e8ves. Lisa Hand, enseignante de CM2, souligne \u00e0 quel point l\u2019histoire de Brad, \u201d The Eye of the Storm \", a raviv\u00e9 chez ses \u00e9l\u00e8ves la passion pour les livres et les r\u00e9cits. L\u2019impact de sa pr\u00e9sentation a \u00e9t\u00e9 profond, et son style captivant ainsi que sa capacit\u00e9 \u00e0 insuffler de la confiance ont \u00e9t\u00e9 salu\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9l\u00e8ves ont partag\u00e9 avec enthousiasme leurs impressions sur \" L'\u0153il de la temp\u00eate \", soulignant l'impact profond de cette histoire qui renforce l'estime de soi. Les jeunes lecteurs ont f\u00e9licit\u00e9 Brad pour avoir su maintenir un r\u00e9cit captivant et dynamique, et ont mis en avant les pr\u00e9cieuses le\u00e7ons de vie tiss\u00e9es dans l'intrigue : la pers\u00e9v\u00e9rance, la responsabilit\u00e9, le leadership et la capacit\u00e9 \u00e0 surmonter ses erreurs pass\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La capacit\u00e9 de Brad \u00e0 captiver l'imagination des jeunes lecteurs transpara\u00eet clairement dans les lettres sinc\u00e8res que lui adressent les \u00e9l\u00e8ves. Leur enthousiasme pour \" The Eye of the Storm \" t\u00e9moigne non seulement de la qualit\u00e9 litt\u00e9raire de l'ouvrage, mais aussi de son influence dans le d\u00e9veloppement du courage, de la r\u00e9silience et de l'amour de la lecture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les enseignants ont utilis\u00e9 \u201c The Eye of the Storm \u201d pour enrichir leur programme scolaire et susciter un int\u00e9r\u00eat pour la r\u00e9flexion critique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Invitez Brad virtuellement dans votre classe pour stimuler la lecture, l'\u00e9criture, la pens\u00e9e cr\u00e9ative, la r\u00e9solution de probl\u00e8mes, les \u00e9clats de rire spontan\u00e9s\u2026<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un parcours plac\u00e9 sous le signe de la r\u00e9silience et de l'autonomisation<\/strong><\/h2>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Une grande partie des connaissances qui ont transform\u00e9 la vie de Brad provient de son exp\u00e9rience. Il n'est pas \u00e9tranger \u00e0 l'adversit\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le parcours personnel de Brad, marqu\u00e9 par des conflits au sein de sa famille d\u2019origine et un diagnostic de cancer \u00e0 l\u2019\u00e2ge de 15 ans, t\u00e9moigne de sa r\u00e9silience d\u00e8s son plus jeune \u00e2ge. Son entr\u00e9e dans un club de kung-fu Shaolin a \u00e9t\u00e9 pour lui une exp\u00e9rience transformatrice. Le kung-fu lui a permis de d\u00e9couvrir des principes et des pratiques pour apaiser d\u2019anciennes blessures \u00e9motionnelles et trouver un \u00ab \u00e9quilibre dynamique \u00bb face aux \u00e9preuves de la vie. Au fil de ses ann\u00e9es d\u2019entra\u00eenement, Brad a d\u00e9velopp\u00e9 une force int\u00e9rieure alli\u00e9e \u00e0 une douceur ext\u00e9rieure, devenant ainsi un professeur inspirant qui aide ses \u00e9l\u00e8ves \u00e0 surmonter les d\u00e9fis et \u00e0 vivre pleinement leur potentiel.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"http:\/\/antiquewhite-albatross-611666.hostingersite.com\/wp-content\/uploads\/2023\/12\/Blakelock-Ba-Duan-Jin.jpg\" alt=\"\" class=\"wp-image-15814\"\/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Brad a \u00e9crit et publi\u00e9 quatre ouvrages ; son dernier ouvrage, co\u00e9crit, intitul\u00e9 \u201c Dynamic Balance, The Tao of Personal and Social Transformations \u201d, met en synergie les principes et les pratiques inh\u00e9rents \u00e0 l'ensemble de ses enseignements.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brad travaille actuellement dans le domaine de la sant\u00e9 mentale en tant que formateur expert chez LivingWorks (ASIST) ; il anime des programmes de pleine conscience destin\u00e9s \u00e0 des associations locales (ax\u00e9s sur l\u2019\u00e9puisement compassionnel et le traumatisme vicariant) et a r\u00e9cemment fait une pr\u00e9sentation lors du congr\u00e8s de la Soci\u00e9t\u00e9 internationale pour la pr\u00e9vention de la maltraitance et de la n\u00e9gligence envers les enfants (ISPCAN) \u00e0 \u00c9dimbourg, en \u00c9cosse. Brad est \u00e9galement en train d'\u00e9crire son prochain livre.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conclusion : Brad Hutchinson \u2014 Un catalyseur de l'\u00e9ducation transformatrice<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Les programmes de pleine conscience de Brad Hutchinson et son expertise litt\u00e9raire promettent une exp\u00e9rience enrichissante et transformatrice aux \u00e9l\u00e8ves du primaire. Fort d\u2019une grande exp\u00e9rience et anim\u00e9 par une passion pour le bien-\u00eatre des \u00e9l\u00e8ves et du personnel, Brad est bien plac\u00e9 pour jouer un r\u00f4le moteur dans la promotion de la pleine conscience, de la r\u00e9silience et de l\u2019optimisme dans le milieu scolaire.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9servez votre programme d\u00e8s aujourd'hui<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/joinus.digitalhumanlibrary.com\/login_view\" target=\"_blank\" rel=\"noopener\" title=\"\">Se connecter \u00e0 la Biblioth\u00e8que humaine num\u00e9rique<\/a> et r\u00e9servez d\u00e8s aujourd'hui votre programme avec Brad !<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Mindful Classrooms In the dynamic landscape of education, the imperative to nurture resilience, compassion, and self-awareness among students has never been more crucial. Brad Hutchinson, a seasoned community leader with over two decades of transformative practices, emerges as a guiding light in this journey. As a Shaolin Kung Fu teacher, author, and advocate for student [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[62],"tags":[],"class_list":["post-12610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dhl-blog"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/digitalhumanlibrary.com\/wp-content\/uploads\/2026\/06\/ASIST-1.jpg","_links":{"self":[{"href":"https:\/\/digitalhumanlibrary.com\/fr\/wp-json\/wp\/v2\/posts\/12610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalhumanlibrary.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digitalhumanlibrary.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digitalhumanlibrary.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digitalhumanlibrary.com\/fr\/wp-json\/wp\/v2\/comments?post=12610"}],"version-history":[{"count":0,"href":"https:\/\/digitalhumanlibrary.com\/fr\/wp-json\/wp\/v2\/posts\/12610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digitalhumanlibrary.com\/fr\/wp-json\/wp\/v2\/media\/11397"}],"wp:attachment":[{"href":"https:\/\/digitalhumanlibrary.com\/fr\/wp-json\/wp\/v2\/media?parent=12610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digitalhumanlibrary.com\/fr\/wp-json\/wp\/v2\/categories?post=12610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digitalhumanlibrary.com\/fr\/wp-json\/wp\/v2\/tags?post=12610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}