{"id":12604,"date":"2023-10-17T00:00:00","date_gmt":"2023-10-17T00:00:00","guid":{"rendered":"https:\/\/digitalhumanlibrary.com\/welcome-new-dhl-expert-you-can-play\/"},"modified":"2023-10-17T00:00:00","modified_gmt":"2023-10-17T00:00:00","slug":"welcome-new-dhl-expert-you-can-play","status":"publish","type":"post","link":"https:\/\/digitalhumanlibrary.com\/es\/welcome-new-dhl-expert-you-can-play\/","title":{"rendered":"Welcome NEW dHL Expert &#8216;You Can Play&#8217;"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El proyecto \u00abYou Can Play\u00bb, una organizaci\u00f3n sin \u00e1nimo de lucro norteamericana dedicada a la promoci\u00f3n del deporte, se complace en anunciar su colaboraci\u00f3n con Digital Human Library.&nbsp;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Acerca de \u00abYou Can Play\u00bb<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La misi\u00f3n de You Can Play es garantizar la seguridad y la inclusi\u00f3n de todas las personas LGBTQ en el deporte, incluidos los deportistas, los entrenadores, el personal y los aficionados. Creemos que fomentar entornos deportivos libres de juicios y discriminaci\u00f3n por motivos de orientaci\u00f3n sexual, identidad de g\u00e9nero y\/o expresi\u00f3n de g\u00e9nero es fundamental para garantizar la seguridad de las personas, as\u00ed como para proteger el sector deportivo. El 24% de los j\u00f3venes LGBTQ afirma practicar alg\u00fan deporte en el colegio, frente al 68% del total de j\u00f3venes.&nbsp;<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/antiquewhite-albatross-611666.hostingersite.com\/wp-content\/uploads\/2023\/09\/homepage-1-to-pride.webp\" alt=\"\" class=\"wp-image-15573\" width=\"255\" height=\"255\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto \u00abYou Can Play\u00bb es una organizaci\u00f3n dedicada a la defensa de los derechos que ofrece programas educativos centrados en los conceptos b\u00e1sicos del apoyo a la comunidad, el apoyo a los deportistas y la inclusi\u00f3n en lo que respecta a deportes espec\u00edficos y a los roles que estos implican. Nuestro contenido tiene como objetivo transformar la cultura en los vestuarios y entre los espectadores, optimizar las pol\u00edticas de inclusi\u00f3n y aumentar la participaci\u00f3n en el deporte entre los j\u00f3venes LGBTQ. A trav\u00e9s de nuestro trabajo, facilitamos un acceso m\u00e1s seguro al deporte y tendemos puentes entre las marcas deportivas y la comunidad LGBTQ.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">You Can Play ofrece los siguientes programas a trav\u00e9s de Digital Human Library y se complace en ponerlos a disposici\u00f3n de los educadores de Norteam\u00e9rica:<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Introducci\u00f3n al apoyo a las personas (formaci\u00f3n de 40 minutos)<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Terminolog\u00eda e identidades LGBTQIA+<\/li>\n\n\n\n<li>Taller sobre lenguaje y redacci\u00f3n<\/li>\n\n\n\n<li>Interseccionalidad, intenci\u00f3n e impacto<\/li>\n\n\n\n<li>Resumen de los espacios inclusivos<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Charla sobre carreras profesionales (30 minutos - 1 hora)<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reuni\u00f3n con el director de Educaci\u00f3n&nbsp;<\/li>\n\n\n\n<li>Elaboraci\u00f3n de recursos educativos<\/li>\n\n\n\n<li>Programaci\u00f3n de la lluvia de ideas&nbsp;<\/li>\n\n\n\n<li>Trabajar en el sector deportivo&nbsp;<\/li>\n\n\n\n<li>Reducir la brecha de inclusi\u00f3n en el \u00e1mbito profesional<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00e1s informaci\u00f3n:<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Descubre aqu\u00ed m\u00e1s recursos sobre la labor de You Can Play en materia de inclusi\u00f3n, as\u00ed como recursos generales sobre c\u00f3mo ser un aliado: <a href=\"https:\/\/drive.google.com\/file\/d\/1abfekbRkZQR5KsEG3gqUm5BFOut6mvNv\/view?usp=drive_link\" target=\"_blank\" rel=\"noopener\" title=\"\">Puedes jugar a \u00abOne-Pager\u00bb (General).pdf<\/a><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para obtener m\u00e1s informaci\u00f3n sobre el proyecto \u00abYou Can Play\u00bb, visita su p\u00e1gina web: <a href=\"https:\/\/www.youcanplayproject.org\/\">https:\/\/www.youcanplayproject.org\/<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>The You Can Play Project, a North American non-profit organization centered around sports advocacy, is thrilled to partner with Digital Human Library.&nbsp; About You Can Play You Can Play&#8217;s mission is to ensure the safety and inclusion of all LGBTQ people in sports, including athletes, coaches, staff and fans. We believe that fostering athletic environments [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[62],"tags":[],"class_list":["post-12604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dhl-blog"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/digitalhumanlibrary.com\/wp-content\/uploads\/2026\/06\/dHL-Featured-Image-YouCanPlay-1.png","_links":{"self":[{"href":"https:\/\/digitalhumanlibrary.com\/es\/wp-json\/wp\/v2\/posts\/12604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalhumanlibrary.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digitalhumanlibrary.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digitalhumanlibrary.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/digitalhumanlibrary.com\/es\/wp-json\/wp\/v2\/comments?post=12604"}],"version-history":[{"count":0,"href":"https:\/\/digitalhumanlibrary.com\/es\/wp-json\/wp\/v2\/posts\/12604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digitalhumanlibrary.com\/es\/wp-json\/wp\/v2\/media\/11381"}],"wp:attachment":[{"href":"https:\/\/digitalhumanlibrary.com\/es\/wp-json\/wp\/v2\/media?parent=12604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digitalhumanlibrary.com\/es\/wp-json\/wp\/v2\/categories?post=12604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digitalhumanlibrary.com\/es\/wp-json\/wp\/v2\/tags?post=12604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}